{"id":16829,"date":"2017-09-19T00:09:26","date_gmt":"2017-09-18T22:09:26","guid":{"rendered":"http:\/\/www.sonicsoulreviews.com\/?p=16829"},"modified":"2017-09-19T00:09:26","modified_gmt":"2017-09-18T22:09:26","slug":"antwyn-jackson-miles-davis","status":"publish","type":"post","link":"https:\/\/www.sonicsoulreviews.com\/wordpress\/2017\/09\/19\/antwyn-jackson-miles-davis\/","title":{"rendered":"ANTWYN JACKSON  &#8222;Miles Davis&#8220;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-content\/uploads\/2017\/09\/Antwyn-Jackson-1.jpg\" alt=\"\" width=\"300\" height=\"301\" class=\"aligncenter size-full wp-image-16833\" srcset=\"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-content\/uploads\/2017\/09\/Antwyn-Jackson-1.jpg 300w, https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-content\/uploads\/2017\/09\/Antwyn-Jackson-1-150x150.jpg 150w, https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-content\/uploads\/2017\/09\/Antwyn-Jackson-1-299x300.jpg 299w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>&#8222;The Birth of Cool&#8220;. Nat\u00fcrlich Miles Davis. Hier der Anfang einer Beziehung. Antwyn Jackson m\u00f6chte die Person seiner Wahl gern n\u00e4her<!--more--> kennenlernen &#8211; &#8222;The Birth Of Cool&#8220; leitet diese Phase des Spiels ein und gibt uns dazu einen ganz abgehangenen Beat dazu. Ganz feines Soul-Jazz Angebot.<\/p>\n<p><iframe loading=\"lazy\" width=\"100%\" height=\"150\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/www.reverbnation.com\/widget_code\/html_widget\/artist_5081723?widget_id=55&#038;pwc[song_ids]=28523220&#038;context_type=song&#038;pwc[size]=small&#038;pwc[branded]=1\" style=\"width:0px;min-width:100%;max-width:100%;\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;The Birth of Cool&#8220;. Nat\u00fcrlich Miles Davis. Hier der Anfang einer Beziehung. Antwyn Jackson m\u00f6chte die Person seiner Wahl gern n\u00e4her<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,7],"tags":[108,28,13,38],"class_list":["post-16829","post","type-post","status-publish","format-standard","hentry","category-preview","category-reviews","tag-108","tag-sonic-soul","tag-soul","tag-vocals"],"_links":{"self":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts\/16829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/comments?post=16829"}],"version-history":[{"count":7,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts\/16829\/revisions"}],"predecessor-version":[{"id":16842,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts\/16829\/revisions\/16842"}],"wp:attachment":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/media?parent=16829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/categories?post=16829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/tags?post=16829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}