{"id":1214,"date":"2011-06-14T18:01:25","date_gmt":"2011-06-14T17:01:25","guid":{"rendered":"http:\/\/www.sonicsoulreviews.com\/?p=1214"},"modified":"2015-01-07T15:21:07","modified_gmt":"2015-01-07T14:21:07","slug":"deidre-gaddis-%e2%80%9elife-key-dei%e2%80%9c-111-east","status":"publish","type":"post","link":"https:\/\/www.sonicsoulreviews.com\/wordpress\/2011\/06\/14\/deidre-gaddis-%e2%80%9elife-key-dei%e2%80%9c-111-east\/","title":{"rendered":"DEIDRE GADDIS     \u201eLife In The Key Of Dei\u201c                                          (111 East)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-1215\" title=\"Deidre Gaddis\" src=\"https:\/\/dl.dropboxusercontent.com\/u\/21762022\/wordpress_images\/2011\/06\/Deidre-Gaddis-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-content\/uploads\/2011\/06\/Deidre-Gaddis-150x150.jpg 150w, https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-content\/uploads\/2011\/06\/Deidre-Gaddis.jpg 200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><br \/>\nBrian \u2018B-Flat Trax\u2019 Cook und Will aka Slick und Dboi. Aha. Klingt ja toll, nicht wahr? Nat\u00fcrlich sollte erst einmal eine gewisse Skepsis walten, wenn es gilt \u00fcber Musiken zu urteilen, die von einem derart illustren Trio zugeschnitten wurde. Im Fall der hier zu besprechenden Deidre Gaddis hat aber schon der H\u00f6r-Genu\u00df der vorab unter den einschl\u00e4gigen Geschmacksverwaltern verteilten Single \u201eThis Funky Ride Of Life\u201c jeglichen Abwehrmechanismus obsolet werden lassen.<!--more--> Einem derart zur\u00fcckgelehnt angebotenem Groover kann man einfach nicht widerstehen \u2013 gem\u00fctlich schwankendes Midtempo, dar\u00fcber einige jazzbestimmte Harmonien und eine Hookline, die sich nachhaltig an den entscheidenden Schaltstellen verhakt. Also, gro\u00dfe Erwartung, statt armverschr\u00e4nktes Abwarten. Doch die eingangs namentlich erw\u00e4hnten Herren erweisen sich als unerbittlich und verpassen der gro\u00dfformatigen Dame ein deutlich zu enges Korsett aus stetig klickenden Beatz, knappen Elektronikfasern und irgendwo hinsteuernden Melodeien \u2013 bei Gelegenheit angereichert mit verzierenden Samples und immer wieder gern von einem immer gleichen Gl\u00fccksrad-Soundeffekt eingeleitet. Dabei versteht es Frau Gaddis ihre Stimme in die verschiedensten Stimmungslagen effektvoll einzubringen \u2013 ein Potential, dass der Betreuerstab aber gar zu selten im Sinne von \u201eThis Funky Ride\u2026\u201c einzusetzen wei\u00df. Klarstellung: \u201eLife In The Key Of die\u201c ist eine tagesaktuelle R&amp;B Produktion, der es in ihren besten Momenten gelingt den Weg aus dem selbstgew\u00e4hlten Sound-Ghetto zu weisen. Deidre wei\u00df, was zu tun ist.<\/p>\n<p>Wertung: 7,5\/10<br \/>\nKaufen:   <a href=\"http:\/\/www.cdbaby.com\/cd\/deirdregaddis3\">www.cdbaby.com\/cd\/deirdregaddis3<\/a><br \/>\nInfo:       <a href=\"http:\/\/www.missdeirdregaddis.virb.com\/\">www.missdeirdregaddis.virb.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brian \u2018B-Flat Trax\u2019 Cook und Will aka Slick und Dboi. Aha. Klingt ja toll, nicht wahr? Nat\u00fcrlich sollte erst einmal eine gewisse Skepsis walten, wenn es gilt \u00fcber Musiken zu urteilen, die von einem derart illustren Trio zugeschnitten wurde. Im &hellip; <a href=\"https:\/\/www.sonicsoulreviews.com\/wordpress\/2011\/06\/14\/deidre-gaddis-%e2%80%9elife-key-dei%e2%80%9c-111-east\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[12],"class_list":["post-1214","post","type-post","status-publish","format-standard","hentry","category-grooves-beatz","tag-12"],"_links":{"self":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts\/1214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/comments?post=1214"}],"version-history":[{"count":4,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts\/1214\/revisions"}],"predecessor-version":[{"id":9200,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts\/1214\/revisions\/9200"}],"wp:attachment":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/media?parent=1214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/categories?post=1214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/tags?post=1214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}