{"id":11505,"date":"2015-08-05T22:42:17","date_gmt":"2015-08-05T21:42:17","guid":{"rendered":"http:\/\/www.sonicsoulreviews.com\/?p=11505"},"modified":"2015-08-05T22:42:17","modified_gmt":"2015-08-05T21:42:17","slug":"the-foreign-exchange-asking-for-a-friend","status":"publish","type":"post","link":"https:\/\/www.sonicsoulreviews.com\/wordpress\/2015\/08\/05\/the-foreign-exchange-asking-for-a-friend\/","title":{"rendered":"THE FOREIGN EXCHANGE  &#8222;Asking For A Friend&#8220;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/db.tt\/CbVtCOM3\" class=\"aligncenter\" width=\"300\" height=\"300\" \/>Fr\u00f6hlich ist das Arbeitsleben. The Foreign Exchange, die allseits angesehene Allstar-Combo des neuen Soul zeigt uns wie der Spa\u00df im B\u00fcro funktionieren kann.<!--more--> Hier kommt zusammen, was zusammen geh\u00f6rt &#8211; eingepackt in einem flott-pointierten Dance-Beat und umgesetzt von bestens aufgelegten Akteuren. Das neue Album mit dem vielversprechenden Titel &#8222;Tales From The Land Of Milk And Honey&#8220; folgt am 21.08. &#8211; ein sicherer Hit!<\/p>\n<p><iframe loading=\"lazy\" title=\"The Foreign Exchange - Asking For A Friend (Official Video)\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/JHctH4s80rs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fr\u00f6hlich ist das Arbeitsleben. The Foreign Exchange, die allseits angesehene Allstar-Combo des neuen Soul zeigt uns wie der Spa\u00df im B\u00fcro funktionieren kann.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,7],"tags":[46,52,34,27,43],"class_list":["post-11505","post","type-post","status-publish","format-standard","hentry","category-preview","category-reviews","tag-46","tag-dance","tag-hit","tag-nu-school","tag-spas"],"_links":{"self":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts\/11505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/comments?post=11505"}],"version-history":[{"count":3,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts\/11505\/revisions"}],"predecessor-version":[{"id":11508,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/posts\/11505\/revisions\/11508"}],"wp:attachment":[{"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/media?parent=11505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/categories?post=11505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sonicsoulreviews.com\/wordpress\/wp-json\/wp\/v2\/tags?post=11505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}